{"id":282,"date":"2025-02-08T06:10:34","date_gmt":"2025-02-08T06:10:34","guid":{"rendered":"https:\/\/cn-hawe.com\/?page_id=282"},"modified":"2025-02-11T07:10:46","modified_gmt":"2025-02-11T07:10:46","slug":"dual-table-fiber-laser-cutting-machine","status":"publish","type":"page","link":"https:\/\/cn-hawe.com\/es\/laser-cutting-machine\/dual-table-fiber-laser-cutting-machine\/","title":{"rendered":"Serie HLB M\u00e1quina de Corte por L\u00e1ser de Fibra de Mesa Doble"},"content":{"rendered":"<section class=\"bde-section-282-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-282-101 bde-columns\"><div class=\"bde-column-282-102 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-104 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HLB-Series-Dual-table-Laser-Cutting.webp\" alt=\"M\u00e1quina de Corte L\u00e1ser de Fibra de Doble Mesa Serie HLB\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HLB-Series-Dual-table-Laser-Cutting.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HLB-Series-Dual-table-Laser-Cutting-300x250.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HLB-Series-Dual-table-Laser-Cutting-1024x853.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HLB-Series-Dual-table-Laser-Cutting-768x640.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><div class=\"bde-column-282-103 bde-column\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-282-105 bde-heading\">\nM\u00e1quina de Corte L\u00e1ser de Fibra de Doble Mesa Serie HLB\n<\/h1><div class=\"bde-fancy-divider-282-106 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-107 bde-text\">\nLa m\u00e1quina de corte l\u00e1ser de la serie CN-HAWE HLB es una soluci\u00f3n avanzada y eficiente dise\u00f1ada para el procesamiento profesional y de gran volumen de l\u00e1minas met\u00e1licas delgadas. Su dise\u00f1o modular y estructura con ensamblaje de espiga y mortaja garantizan una estabilidad y robustez superiores. Con una viga transversal de aluminio de alta resistencia, la m\u00e1quina destaca en rendimiento din\u00e1mico. La estructura totalmente cerrada, junto con un sistema de doble plataforma, promueve una producci\u00f3n segura y eficiente. Dise\u00f1ada para un corte econ\u00f3mico, r\u00e1pido y preciso de acero al carbono y acero inoxidable, esta m\u00e1quina cuenta con un sistema de control por bus orientado al usuario para una operaci\u00f3n fluida y de funcionamiento confiable.\n<\/div><img decoding=\"async\" class=\"bde-image2-282-108 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp 387w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s-300x81.webp 300w\" sizes=\"(max-width: 387px) 100vw, 387px\"><div class=\"bde-button-282-109 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">CONSULTE AHORA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-282-110 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-282-121 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-111 bde-columns\"><div class=\"bde-column-282-115 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-116 bde-heading\">\nFuente l\u00e1ser\n<\/h2><div class=\"bde-fancy-divider-282-117 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-118 bde-text\">\nNuestra m\u00e1quina de corte l\u00e1ser cuenta con un generador l\u00e1ser de fibra de \u00faltima tecnolog\u00eda, conocido por su eficiencia y fiabilidad excepcionales. Esta innovadora fuente l\u00e1ser produce un haz estable y potente, permitiendo cortes precisos y suaves en diversos materiales. Su dise\u00f1o prioriza el ahorro energ\u00e9tico y la durabilidad, ayudando a reducir los costos operativos y simplificar el mantenimiento. La construcci\u00f3n compacta y s\u00f3lida del generador l\u00e1ser asegura una f\u00e1cil integraci\u00f3n en nuestra m\u00e1quina, mejorando su funcionalidad y robustez general. Las principales marcas incluyen Raycus, Maxphotonics, IPG y nLIGHT.\n<\/div><div class=\"bde-button-282-120 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-113 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-114 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Laser-Source.webp\" alt=\"Fuente l\u00e1ser\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Laser-Source.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Laser-Source-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Laser-Source-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Laser-Source-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-149 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-150 bde-columns\"><div class=\"bde-column-282-151 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-152 bde-heading\">\nCabezal de corte\n<\/h2><div class=\"bde-fancy-divider-282-153 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-154 bde-text\">\nLa cabeza de corte de la serie l\u00e1ser CN-HAWE est\u00e1 dise\u00f1ada para ser ligera y compacta, lo que mejora la eficiencia de movimiento y permite mayores velocidades con superior aceleraci\u00f3n. Su estructura sellada protege la \u00f3ptica interna, asegurando durabilidad y rendimiento confiable a largo plazo. Adem\u00e1s, el sistema optimizado de flujo de gas admite tanto gases de proceso de baja como de alta presi\u00f3n, haci\u00e9ndola adaptable a una amplia variedad de tareas de corte. Equipada con un mecanismo inteligente anti-colisi\u00f3n y capacidades avanzadas de detecci\u00f3n de bordes, la cabeza de corte mejora la seguridad y precisi\u00f3n durante la operaci\u00f3n. En conjunto, estas caracter\u00edsticas permiten un rendimiento de alta velocidad, respuesta din\u00e1mica excepcional y aceleraci\u00f3n r\u00e1pida, ofreciendo precisi\u00f3n y eficiencia para diversas aplicaciones de corte.\n<\/div><div class=\"bde-button-282-235 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-156 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-157 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Cutting-Head1.webp\" alt=\"Cabezal de corte\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Cutting-Head1.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Cutting-Head1-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Cutting-Head1-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Cutting-Head1-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-158 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-159 bde-columns\"><div class=\"bde-column-282-160 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-161 bde-heading\">\nViga\n<\/h2><div class=\"bde-fancy-divider-282-162 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-163 bde-text\">\nLa viga transversal de nuestra m\u00e1quina de corte l\u00e1ser est\u00e1 cuidadosamente dise\u00f1ada con ayuda del an\u00e1lisis de elementos finitos para lograr un equilibrio ideal entre rigidez y ligereza. Esta optimizaci\u00f3n avanzada mejora el rendimiento de la m\u00e1quina, permitiendo una operaci\u00f3n a alta velocidad, estabilidad din\u00e1mica excepcional y r\u00e1pida aceleraci\u00f3n, manteniendo al mismo tiempo precisi\u00f3n y eficiencia en las tareas de corte.\n<\/div><div class=\"bde-button-282-236 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-165 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-166 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Beam.webp\" alt=\"Viga\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Beam.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Beam-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Beam-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Beam-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-167 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-168 bde-columns\"><div class=\"bde-column-282-169 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-170 bde-heading\">\nSistema operativo\n<\/h2><div class=\"bde-fancy-divider-282-171 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-172 bde-text\">\nNuestro software de corte, basado en la plataforma Cypcut, es una soluci\u00f3n potente e intuitiva para el corte l\u00e1ser de fibra, dise\u00f1ada para maximizar la eficiencia y rendimiento de nuestras m\u00e1quinas. Destaca por su instalaci\u00f3n sin complicaciones, depuraci\u00f3n sencilla y funcionalidad excepcional. El software permite ajustes de velocidad basados en la potencia y admite configuraciones independientes de velocidad lineal, ofreciendo a los usuarios una versatilidad mejorada. Adem\u00e1s, su amplia base de datos de procesos de corte garantiza resultados precisos y confiables en una amplia gama de aplicaciones.\n<\/div><div class=\"bde-button-282-237 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-174 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-175 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Operating-System.webp\" alt=\"Sistema operativo\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Operating-System.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Operating-System-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Operating-System-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Operating-System-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-176 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-177 bde-columns\"><div class=\"bde-column-282-178 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-179 bde-heading\">\nEstructura de la cama\n<\/h2><div class=\"bde-fancy-divider-282-180 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-181 bde-text\">\nEl modelo HLB de m\u00e1quina de corte l\u00e1ser est\u00e1 equipado con un bastidor dise\u00f1ado para ser compacto y estable, ofreciendo facilidad de operaci\u00f3n y una utilizaci\u00f3n \u00f3ptima del espacio. Su construcci\u00f3n con ensamblaje de espiga y mortaja asegura durabilidad prolongada e integridad estructural. Adem\u00e1s, la integraci\u00f3n modular del gabinete el\u00e9ctrico, gabinete l\u00e1ser, sistema de gas y circuito de aceite mejora tanto la fiabilidad como la facilidad de mantenimiento. Combinado con el avanzado sistema de control por bus, este dise\u00f1o robusto ofrece un rendimiento inteligente, eficiente y f\u00e1cil de usar.\n<\/div><div class=\"bde-button-282-238 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-183 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-184 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Bed-Frame.webp\" alt=\"Estructura de la cama\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Bed-Frame.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Bed-Frame-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Bed-Frame-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Bed-Frame-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-185 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-186 bde-columns\"><div class=\"bde-column-282-187 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-188 bde-heading\">\nEnfriador de agua\n<\/h2><div class=\"bde-fancy-divider-282-189 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-190 bde-text\">\nEl sistema de enfriamiento por agua que acompa\u00f1a a nuestra m\u00e1quina de corte por l\u00e1ser est\u00e1 equipado con funciones como alertas de sobretemperatura, monitoreo de flujo, protecci\u00f3n del nivel de agua y notificaciones de alarmas de seguridad.\n<\/div><div class=\"bde-button-282-239 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-192 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-193 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Water-Chiller.webp\" alt=\"Enfriador de agua\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Water-Chiller.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Water-Chiller-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Water-Chiller-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Water-Chiller-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-244 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-245 bde-columns\"><div class=\"bde-column-282-246 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-247 bde-heading\">\nLubricaci\u00f3n autom\u00e1tica\n<\/h2><div class=\"bde-fancy-divider-282-248 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-249 bde-text\">\nEl sistema de lubricaci\u00f3n autom\u00e1tica funciona a intervalos programados en sincron\u00eda con la operaci\u00f3n de la m\u00e1quina, suministrando aceite lubricante autom\u00e1ticamente para un mantenimiento eficiente y sin complicaciones. Esto mejora significativamente la vida \u00fatil de la m\u00e1quina.\n<\/div><div class=\"bde-button-282-250 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-251 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-252 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Auto-Lubrication.webp\" alt=\"Lubricaci\u00f3n autom\u00e1tica\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Auto-Lubrication.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Auto-Lubrication-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Auto-Lubrication-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Auto-Lubrication-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-282-253 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-282-254 bde-columns\"><div class=\"bde-column-282-255 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-282-256 bde-heading\">\nEnfriador de aire\n<\/h2><div class=\"bde-fancy-divider-282-257 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-282-258 bde-text\">\nEl objetivo principal de instalar un enfriador de aire es reducir la temperatura interna del gabinete el\u00e9ctrico, garantizando un funcionamiento constante y fiable. Al eliminar activamente el calor generado por los componentes el\u00e9ctricos, ayuda a prolongar significativamente su vida \u00fatil.\n<\/div><div class=\"bde-button-282-259 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENGA COTIZACI\u00d3N GRATUITA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-282-260 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-282-261 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Air-Cooler.webp\" alt=\"Enfriador de aire\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Air-Cooler.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Air-Cooler-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Air-Cooler-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Air-Cooler-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-282-230 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-fancy-divider-282-232 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator has-content\">\n  \t    \t    \t          <h2 class=\"bde-fancy-divider__content bde-fancy-divider__content--text\">\n          Especificaciones T\u00e9cnicas\n          <\/h2>\n    \t      <\/div>\n<\/div>\n\n<\/div><div class=\"bde-shortcodewrapper-282-234 bde-shortcodewrapper\">\n<table id=\"tablepress-8\" class=\"tablepress tablepress-id-8\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><br \/>\n                                        Modelo                    <\/th><th class=\"column-2\"><br \/>\n                                        HLB3015                    <\/th><th class=\"column-3\"><br \/>\n                                        HLB4020                    <\/th><th class=\"column-4\"><br \/>\n                                        HLB6025                    <\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><br \/>\n                                        \u00c1rea de procesamiento                    <\/td><td class=\"column-2\"><br \/>\n                                        3000mmX1500mm                    <\/td><td class=\"column-3\"><br \/>\n                                        4000mmX2000mm                    <\/td><td class=\"column-4\"><br \/>\n                                        6000mmX2500mm                    <\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><br \/>\n                                        Precisi\u00f3n de posicionamiento del eje X\/Y                    <\/td><td class=\"column-2\"><br \/>\n                                        \u00b10.03mm\/m                    <\/td><td class=\"column-3\"><br \/>\n                                        \u00b10.03mm\/m                    <\/td><td class=\"column-4\"><br \/>\n                                        \u00b10.03mm\/m                    <\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><br \/>\n                                        Precisi\u00f3n de repetici\u00f3n de posicionamiento del eje X\/Y                    <\/td><td class=\"column-2\"><br \/>\n                                        \u00b10.02mm                    <\/td><td class=\"column-3\"><br \/>\n                                        \u00b10.02mm                    <\/td><td class=\"column-4\"><br \/>\n                                        \u00b10.02mm                    <\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><br \/>\n                                        Velocidad m\u00e1xima de posicionamiento del eje X\/Y                    <\/td><td class=\"column-2\"><br \/>\n                                        110m\/min                    <\/td><td class=\"column-3\"><br \/>\n                                        110m\/min                    <\/td><td class=\"column-4\"><br \/>\n                                        140m\/min                    <\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\"><br \/>\n                                        Aceleraci\u00f3n m\u00e1xima del eje X\/Y                    <\/td><td class=\"column-2\"><br \/>\n                                        0.8g                    <\/td><td class=\"column-3\"><br \/>\n                                        0.8g                    <\/td><td class=\"column-4\"><br \/>\n                                        1.0g                    <\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><br \/>\n                                        Carga m\u00e1xima de la mesa de trabajo                    <\/td><td class=\"column-2\"><br \/>\n                                        0.7t                    <\/td><td class=\"column-3\"><br \/>\n                                        1.0t                    <\/td><td class=\"column-4\"><br \/>\n                                        3.0t                    <\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\"><br \/>\n                                        Dimensi\u00f3n (L*a)                    <\/td><td class=\"column-2\"><br \/>\n                                        8700mmX5700mm                    <\/td><td class=\"column-3\"><br \/>\n                                        10800mmX6300mm                    <\/td><td class=\"column-4\"><br \/>\n                                        15000mmX7000mm                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n <\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>HLB Series Dual-Table Fiber Laser Cutting Machine The CN-HAWE HLB series laser cutting machine is an advanced and efficient solution tailored for professional, high-volume processing of thin metal sheets. Its modular design and mortise-and-tenon joint framework ensure superior stability and robustness. With a high-strength aluminum crossbeam, the machine excels in dynamic performance. The fully enclosed [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":105,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-282","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/pages\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":4,"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/pages\/282\/revisions"}],"predecessor-version":[{"id":597,"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/pages\/282\/revisions\/597"}],"up":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/pages\/105"}],"wp:attachment":[{"href":"https:\/\/cn-hawe.com\/es\/wp-json\/wp\/v2\/media?parent=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}