{"id":221,"date":"2025-02-08T05:48:45","date_gmt":"2025-02-08T05:48:45","guid":{"rendered":"https:\/\/cn-hawe.com\/?page_id=221"},"modified":"2025-02-11T08:43:33","modified_gmt":"2025-02-11T08:43:33","slug":"tandem-cnc-press-brake","status":"publish","type":"page","link":"https:\/\/cn-hawe.com\/it\/press-brake\/tandem-cnc-press-brake\/","title":{"rendered":"Piegatrice CNC tandem 2HPA"},"content":{"rendered":"<section class=\"bde-section-221-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-221-101 bde-columns\"><div class=\"bde-column-221-102 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-104 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2HPA-Tandem-CNC-Press-Brake-1.webp\" alt=\"Piegatrice CNC tandem 2HPA\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2HPA-Tandem-CNC-Press-Brake-1.webp 1500w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2HPA-Tandem-CNC-Press-Brake-1-300x200.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2HPA-Tandem-CNC-Press-Brake-1-1024x683.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2HPA-Tandem-CNC-Press-Brake-1-768x512.webp 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\">\n<\/div><div class=\"bde-column-221-103 bde-column\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-221-105 bde-heading\">\nPiegatrice CNC tandem 2HPA\n<\/h1><div class=\"bde-fancy-divider-221-106 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-107 bde-text\">\nLa pressa piegatrice tandem 2HPA \u00e8 progettata con una notevole flessibilit\u00e0, rendendola ideale per gestire una vasta gamma di operazioni di piegatura. Questa macchina eccelle nella gestione della piegatura di pezzi lunghi, come pali luminosi da 12 metri, con precisione e facilit\u00e0. Inoltre, la sua capacit\u00e0 di operare sia in modo indipendente sia in tandem con altre attrezzature ne aumenta l\u2019adattabilit\u00e0, garantendo che soddisfi senza problemi diversi requisiti produttivi e flussi di lavoro.<br><br>Oltre ai suoi punti di forza hardware, la pressa piegatrice della serie 2HPA offre un solido supporto software che svolge un ruolo fondamentale. In collaborazione con CN-HAWE, i produttori dei controllori forniscono ampie librerie applicative e servizi di sviluppo personalizzati, consentendo agli utenti di ottimizzare le impostazioni della macchina in base alle esigenze specifiche. Questi strumenti software avanzati aiutano gli operatori a ottimizzare le sequenze di piegatura, prevedere il ritorno elastico del materiale e ridurre al minimo i processi di tentativo ed errore, aumentando cos\u00ec l\u2019efficienza e migliorando la qualit\u00e0 del prodotto.<br><br>In sintesi, la pressa piegatrice della serie 2HPA \u00e8 diventata una scelta preferita in numerosi settori, in particolare nella lavorazione di grandi componenti metallici, grazie alle sue prestazioni eccezionali e alla sua flessibilit\u00e0. Che venga utilizzata come macchina autonoma o integrata in linee di produzione automatizzate complesse, offre soluzioni efficienti, precise e affidabili.\n<\/div><img decoding=\"async\" class=\"bde-image2-221-108 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp 387w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s-300x81.webp 300w\" sizes=\"(max-width: 387px) 100vw, 387px\"><div class=\"bde-button-221-109 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">RICHIEDI ORA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-221-110 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-221-121 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-111 bde-columns\"><div class=\"bde-column-221-115 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-116 bde-heading\">\nControllore CNC\n<\/h2><div class=\"bde-fancy-divider-221-117 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-118 bde-text\">\nI controllori CNC costituiscono la spina dorsale del controllo del movimento nelle presse piegatrici. Presso CN-HAWE utilizziamo principalmente controllori di tre produttori leader a livello mondiale: Delem dai Paesi Bassi, ESA dall\u2019Italia e Cybelec dalla Svizzera.  <br><br>Una regolazione ottimale \u00e8 essenziale per migliorare la compatibilit\u00e0 tra il controllore e la macchina. Integrando il nostro processo di assemblaggio proprietario con metodi di regolazione all\u2019avanguardia, rendiamo disponibili ai clienti una gamma di funzionalit\u00e0 opzionali premium tra cui scegliere.  <br><br>I controllori CN-HAWE offrono una precisione ed efficienza eccezionali grazie a funzionalit\u00e0 avanzate quali regolazioni dell\u2019angolo in tempo reale, robuste capacit\u00e0 di programmazione 2D\/3D e sofisticato controllo multi-asse, garantendo prestazioni costantemente di alta qualit\u00e0.\n<\/div><div class=\"bde-button-221-120 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-113 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-114 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/1-CNC-Controller02.webp\" alt=\"Controllore CNC\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/1-CNC-Controller02.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/1-CNC-Controller02-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/1-CNC-Controller02-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/1-CNC-Controller02-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-149 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-150 bde-columns\"><div class=\"bde-column-221-151 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-152 bde-heading\">\nRiscontro posteriore\n<\/h2><div class=\"bde-fancy-divider-221-153 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-154 bde-text\">\nIl sistema di riscontro posteriore CN-HAWE guida il settore delle presse piegatrici grazie alla sua eccezionale precisione di movimento. <br><br>Per garantire un\u2019elevata precisione e coerenza nel processo produttivo delle presse piegatrici CNC della serie CN-HAWE, utilizziamo viti a ricircolo di sfere e guide lineari importate. Inoltre, l\u2019intero telaio del registro posteriore \u00e8 sottoposto a rinvenimento ad alta temperatura, un processo che elimina le tensioni interne, migliora la plasticit\u00e0 e la tenacit\u00e0 del metallo e previene il degrado della precisione causato dalla deformazione del telaio nel tempo.<br><br>Per le dita di arresto, abbiamo implementato un meccanismo a puleggia sincrona azionato da un servomotore. Questo design innovativo offre prestazioni e precisione di controllo superiori per il sistema di registro posteriore della pressa piegatrice CNC.\n<\/div><div class=\"bde-button-221-235 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-156 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-157 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2-Back-gauge-1.webp\" alt=\"Riscontro posteriore\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2-Back-gauge-1.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2-Back-gauge-1-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2-Back-gauge-1-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/2-Back-gauge-1-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-158 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-159 bde-columns\"><div class=\"bde-column-221-160 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-161 bde-heading\">\nMotore Servo Principale\n<\/h2><div class=\"bde-fancy-divider-221-162 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-163 bde-text\">\nI servomotori sono emersi come la tecnologia leader nell\u2019automazione industriale, offrendo prestazioni dinamiche eccezionali e aumentando la produttivit\u00e0 della macchina con un consumo energetico minimo. Ci\u00f2 li rende la scelta migliore per molte aziende. Rispetto ai motori convenzionali, i servomotori possono ridurre il consumo energetico fino al 35%, consentendo ai clienti di aumentare significativamente l\u2019efficienza riducendo al contempo i costi di produzione.<br><br>Inoltre, offriamo motori ad alta efficienza e a risparmio energetico di Siemens, un rinomato produttore tedesco, per soddisfare le esigenze di produzione standard dei clienti. Questi motori superano i modelli standard in termini di efficienza, offrendo notevoli miglioramenti nella produttivit\u00e0 operativa. Realizzati con tecnologia all\u2019avanguardia e un design innovativo, garantiscono prestazioni costanti e affidabili in un\u2019ampia gamma di condizioni operative. Sia ad alte che a basse velocit\u00e0, questi motori mantengono un\u2019efficienza e una precisione eccezionali, soddisfacendo le esigenze rigorose dei clienti in termini di efficienza produttiva e qualit\u00e0 del prodotto.\n<\/div><div class=\"bde-button-221-236 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-165 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-166 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/3-Main-Servo-Motor-1.webp\" alt=\"Motore Servo Principale\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/3-Main-Servo-Motor-1.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/3-Main-Servo-Motor-1-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/3-Main-Servo-Motor-1-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/3-Main-Servo-Motor-1-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-167 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-168 bde-columns\"><div class=\"bde-column-221-169 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-170 bde-heading\">\nSistema idraulico servo\n<\/h2><div class=\"bde-fancy-divider-221-171 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-172 bde-text\">\nIl sistema idraulico servo di una pressa piegatrice CNC \u00e8 composto da componenti essenziali come motore, pompa dell\u2019olio, elementi filtranti, gruppo valvole, cilindri idraulici e serbatoio dell\u2019olio. Per garantirne l\u2019affidabilit\u00e0 e le prestazioni, abbiamo collaborato con HAWE, un rinomato produttore tedesco. I loro prodotti sono noti per le prestazioni eccezionali e i bassi tassi di guasto, fornendo una base solida per il nostro sistema.<br><br>Inoltre, il nostro sistema di controllo idraulico utilizza un design a sincronizzazione elettroidraulica servo, che riduce al minimo l\u2019intervallo tra i cilindri idraulici. Questo design migliora la resistenza ai carichi eccentrici, garantisce una sincronizzazione precisa e offre rapporti di densit\u00e0 di potenza eccezionali, mantenendo al contempo l\u2019efficienza dei costi. La pressione del sistema \u00e8 regolabile, consentendogli di soddisfare requisiti variabili di forza di piegatura e adattarsi senza problemi a un\u2019ampia gamma di scenari applicativi pratici.\n<\/div><div class=\"bde-button-221-237 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-174 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-175 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/4-Servo-Hydraulic-System01.webp\" alt=\"Sistema idraulico servo\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/4-Servo-Hydraulic-System01.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/4-Servo-Hydraulic-System01-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/4-Servo-Hydraulic-System01-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/4-Servo-Hydraulic-System01-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-176 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-177 bde-columns\"><div class=\"bde-column-221-178 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-179 bde-heading\">\nPompa dell\u2019olio\n<\/h2><div class=\"bde-fancy-divider-221-180 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-181 bde-text\">\nLa pompa dell\u2019olio CN-HAWE \u00e8 realizzata in ghisa ad alta resistenza, garantendo maggiore stabilit\u00e0 e affidabilit\u00e0 durante il funzionamento, oltre a consentirle di sopportare alta pressione e carichi pesanti. Il suo design interno innovativo incorpora una struttura meccanica precisa e un flusso di processo ottimizzato, aumentando significativamente l\u2019efficienza e le prestazioni complessive della pompa.<br><br>Una delle caratteristiche distintive di questa pompa dell\u2019olio \u00e8 la sua capacit\u00e0 di riduzione del rumore, che minimizza il rumore operativo e crea un ambiente di lavoro pi\u00f9 silenzioso per gli utenti. Inoltre, la pompa mostra una bassa sensibilit\u00e0 alla contaminazione dell\u2019olio, consentendole di funzionare efficacemente anche in condizioni di olio con impurit\u00e0. Questa resistenza alla contaminazione non solo ne migliora la durata, ma ne prolunga significativamente la vita utile.\n<\/div><div class=\"bde-button-221-238 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-183 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-184 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/5-Oil-Pump.webp\" alt=\"Pompa dell\u2019olio\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/5-Oil-Pump.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/5-Oil-Pump-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/5-Oil-Pump-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/5-Oil-Pump-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-185 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-186 bde-columns\"><div class=\"bde-column-221-187 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-188 bde-heading\">\nUtensili Punzone &amp; Matrice\n<\/h2><div class=\"bde-fancy-divider-221-189 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-190 bde-text\">\nPrima di effettuare un ordine, \u00e8 fondamentale considerare attentamente la selezione di punzoni e matrici appropriati per la pressa piegatrice. Scegliere la giusta combinazione \u00e8 la chiave per ottenere i risultati di piegatura desiderati. In particolare per i modelli tandem pesanti 2HPA, offriamo utensili completamente personalizzabili progettati per soddisfare requisiti specifici. Questo approccio personalizzato non solo soddisfa le esigenze dei clienti, ma aiuta anche a evitare complicazioni inutili. Le nostre soluzioni di utensileria personalizzate sono realizzate con precisione per corrispondere esattamente alle specifiche di piegatura fornite dai nostri clienti.\n<\/div><div class=\"bde-button-221-239 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-192 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-193 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/6-Punch-Die-Tools-1.webp\" alt=\"Utensili Punzone &amp; Matrice\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/6-Punch-Die-Tools-1.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/6-Punch-Die-Tools-1-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/6-Punch-Die-Tools-1-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/6-Punch-Die-Tools-1-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-244 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-245 bde-columns\"><div class=\"bde-column-221-246 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-247 bde-heading\">\nSistema di Bombatura\n<\/h2><div class=\"bde-fancy-divider-221-248 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-249 bde-text\">\nCN-HAWE \u00e8 attualmente specializzata in due linee di prodotti principali: sistemi elettrici di compensazione inferiore e un\u2019ampia gamma di sistemi idraulici di bloccaggio e compensazione superiori e inferiori. Il nostro design innovativo calcola i valori di compensazione valutando la deformazione complessiva del cursore e del banco di lavoro.<br><br>Questo approccio garantisce un allineamento preciso tra la curva di deformazione del cursore e la curva di compensazione, assicurando eccezionale rettilineit\u00e0 e precisione angolare durante la produzione e il funzionamento delle nostre soluzioni per presse piegatrici. Questi progressi non solo dominano una quota significativa del mercato domestico, ma vengono anche esportati in numerosi paesi in tutto il mondo. Inoltre, la nostra collaborazione strategica con il produttore olandese Wila ci consente di offrire prodotti premium e di fascia alta progettati per soddisfare le esigenze specifiche dei mercati europeo e americano.\n<\/div><div class=\"bde-button-221-250 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-251 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-252 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/7-Crowning-System.webp\" alt=\"Sistema di Bombatura\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/7-Crowning-System.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/7-Crowning-System-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/7-Crowning-System-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/7-Crowning-System-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-253 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-254 bde-columns\"><div class=\"bde-column-221-255 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-256 bde-heading\">\nBending Follower\n<\/h2><div class=\"bde-fancy-divider-221-257 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-258 bde-text\">\nLe presse piegatrici presentano due tipi di follower frontali: integrati e da pavimento. Il follower automatico di piegatura \u00e8 completamente integrato nel controllore del sistema CNC, lavorando in perfetta armonia con il ciclo di controllo del movimento della pressa piegatrice. Questa integrazione rende pi\u00f9 sicura ed efficiente la piegatura di grandi lamiere, riducendo significativamente i tempi e i requisiti di manodopera durante l\u2019intero ciclo di vita del prodotto.  <br><br>Quando si tratta di piegare lamiere ultra-lunghe e ultra-spesse, la nostra pressa piegatrice tandem della serie 2HPA offre vantaggi eccezionali. La sua flessibilit\u00e0 e le capacit\u00e0 di regolazione in altezza e posizione consentono un notevole aumento dell\u2019efficienza, rendendola una soluzione ideale per gestire compiti di piegatura cos\u00ec impegnativi.\n<\/div><div class=\"bde-button-221-259 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-260 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-261 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/8-Bending-Follower-.webp\" alt=\"Bending Follower\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/8-Bending-Follower-.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/8-Bending-Follower--300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/8-Bending-Follower--1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/8-Bending-Follower--768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-221-262 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-221-263 bde-columns\"><div class=\"bde-column-221-264 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-221-265 bde-heading\">\nComponente Elettrico\n<\/h2><div class=\"bde-fancy-divider-221-266 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-221-267 bde-text\">\nLe nostre macchine sono costruite con componenti originali Schneider importati dalla Francia, garantendo prestazioni affidabili e durature. Inoltre, sono dotate di parti originali del quadro elettrico Estun, che offrono eccellenti capacit\u00e0 anti-interferenza e assicurano un funzionamento elettrico stabile.\n<\/div><div class=\"bde-button-221-268 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OTTENI UN PREVENTIVO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-221-269 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-221-270 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPA-Flagship-Series-Electrical-Component.webp\" alt=\"Componente Elettrico\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPA-Flagship-Series-Electrical-Component.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPA-Flagship-Series-Electrical-Component-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPA-Flagship-Series-Electrical-Component-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPA-Flagship-Series-Electrical-Component-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-221-230 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-fancy-divider-221-232 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator has-content\">\n  \t    \t    \t          <h2 class=\"bde-fancy-divider__content bde-fancy-divider__content--text\">\n          Specifiche Tecniche\n          <\/h2>\n    \t      <\/div>\n<\/div>\n\n<\/div><img decoding=\"async\" class=\"bde-image2-221-233 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3.webp\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3.webp 1300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-300x92.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-1024x315.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-768x236.webp 768w\" sizes=\"(max-width: 1300px) 100vw, 1300px\"><div class=\"bde-shortcodewrapper-221-234 bde-shortcodewrapper\">\n<table id=\"tablepress-5\" class=\"tablepress tablepress-id-5\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><br \/>\n                                        Modello                    <\/th><th class=\"column-2\"><br \/>\n                                        Forza di Piegatura                    <\/th><th class=\"column-3\"><br \/>\n                                        Lunghezza di piegatura<br \/>\n(A)                    <\/th><th class=\"column-4\"><br \/>\n                                        Serbatoio dell\u2019Olio                    <\/th><th class=\"column-5\"><br \/>\n                                        Velocit\u00e0 di avvicinamento                    <\/th><th class=\"column-6\"><br \/>\n                                        Velocit\u00e0 di avanzamento                    <\/th><th class=\"column-7\"><br \/>\n                                        Velocit\u00e0 di ritorno                    <\/th><th class=\"column-8\"><br \/>\n                                        Distanza tra le colonne<br \/>\n(B)                    <\/th><th class=\"column-9\"><br \/>\n                                        Profondit\u00e0 della gola<br \/>\n(C)                    <\/th><th class=\"column-10\"><br \/>\n                                        Corsa del cursore<br \/>\n(D)                    <\/th><th class=\"column-11\"><br \/>\n                                        Altezza di apertura<br \/>\n(E)                    <\/th><th class=\"column-12\"><br \/>\n                                        Peso                    <\/th><th class=\"column-13\"><br \/>\n                                        Dimensioni                    <\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><br \/>\n                                        Unit\u00e0                    <\/td><td class=\"column-2\"><br \/>\n                                        kN                    <\/td><td class=\"column-3\"><br \/>\n                                        mm                    <\/td><td class=\"column-4\"><br \/>\n                                        L                    <\/td><td class=\"column-5\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-6\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-7\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-8\"><br \/>\n                                        mm                    <\/td><td class=\"column-9\"><br \/>\n                                        mm                    <\/td><td class=\"column-10\"><br \/>\n                                        mm                    <\/td><td class=\"column-11\"><br \/>\n                                        mm                    <\/td><td class=\"column-12\"><br \/>\n                                        Ton                    <\/td><td class=\"column-13\"><br \/>\n                                        L*P*A (mm)                    <\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><br \/>\n                                        2-HPA-220-4100                    <\/td><td class=\"column-2\"><br \/>\n                                        2200                    <\/td><td class=\"column-3\"><br \/>\n                                        4100                    <\/td><td class=\"column-4\"><br \/>\n                                        230                    <\/td><td class=\"column-5\"><br \/>\n                                        180                    <\/td><td class=\"column-6\"><br \/>\n                                        13                    <\/td><td class=\"column-7\"><br \/>\n                                        170                    <\/td><td class=\"column-8\"><br \/>\n                                        3600                    <\/td><td class=\"column-9\"><br \/>\n                                        410                    <\/td><td class=\"column-10\"><br \/>\n                                        220                    <\/td><td class=\"column-11\"><br \/>\n                                        490                    <\/td><td class=\"column-12\"><br \/>\n                                        13                    <\/td><td class=\"column-13\"><br \/>\n                                        4280*1830*2790                    <\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><br \/>\n                                        2-HPA-400-4000                    <\/td><td class=\"column-2\"><br \/>\n                                        4000                    <\/td><td class=\"column-3\"><br \/>\n                                        4000                    <\/td><td class=\"column-4\"><br \/>\n                                        700                    <\/td><td class=\"column-5\"><br \/>\n                                        100                    <\/td><td class=\"column-6\"><br \/>\n                                        8                    <\/td><td class=\"column-7\"><br \/>\n                                        80                    <\/td><td class=\"column-8\"><br \/>\n                                        3100                    <\/td><td class=\"column-9\"><br \/>\n                                        500                    <\/td><td class=\"column-10\"><br \/>\n                                        300                    <\/td><td class=\"column-11\"><br \/>\n                                        610                    <\/td><td class=\"column-12\"><br \/>\n                                                            <\/td><td class=\"column-13\"><br \/>\n                                                            <\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\"><br \/>\n                                        2-HPA-400-5000                    <\/td><td class=\"column-2\"><br \/>\n                                        4000                    <\/td><td class=\"column-3\"><br \/>\n                                        5000                    <\/td><td class=\"column-4\"><br \/>\n                                        700                    <\/td><td class=\"column-5\"><br \/>\n                                        100                    <\/td><td class=\"column-6\"><br \/>\n                                        8                    <\/td><td class=\"column-7\"><br \/>\n                                        80                    <\/td><td class=\"column-8\"><br \/>\n                                        3800                    <\/td><td class=\"column-9\"><br \/>\n                                        500                    <\/td><td class=\"column-10\"><br \/>\n                                        300                    <\/td><td class=\"column-11\"><br \/>\n                                        610                    <\/td><td class=\"column-12\"><br \/>\n                                                            <\/td><td class=\"column-13\"><br \/>\n                                                            <\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\"><br \/>\n                                        2-HPA-400-6000                    <\/td><td class=\"column-2\"><br \/>\n                                        4000                    <\/td><td class=\"column-3\"><br \/>\n                                        6000                    <\/td><td class=\"column-4\"><br \/>\n                                        700                    <\/td><td class=\"column-5\"><br \/>\n                                        100                    <\/td><td class=\"column-6\"><br \/>\n                                        8                    <\/td><td class=\"column-7\"><br \/>\n                                        80                    <\/td><td class=\"column-8\"><br \/>\n                                        4800                    <\/td><td class=\"column-9\"><br \/>\n                                        500                    <\/td><td class=\"column-10\"><br \/>\n                                        300                    <\/td><td class=\"column-11\"><br \/>\n                                        610                    <\/td><td class=\"column-12\"><br \/>\n                                                            <\/td><td class=\"column-13\"><br \/>\n                                                            <\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><br \/>\n                                        2-HPA-500-4000                    <\/td><td class=\"column-2\"><br \/>\n                                        5000                    <\/td><td class=\"column-3\"><br \/>\n                                        4000                    <\/td><td class=\"column-4\"><br \/>\n                                        800                    <\/td><td class=\"column-5\"><br \/>\n                                        100                    <\/td><td class=\"column-6\"><br \/>\n                                        8                    <\/td><td class=\"column-7\"><br \/>\n                                        80                    <\/td><td class=\"column-8\"><br \/>\n                                        3100                    <\/td><td class=\"column-9\"><br \/>\n                                        500                    <\/td><td class=\"column-10\"><br \/>\n                                        300                    <\/td><td class=\"column-11\"><br \/>\n                                        610                    <\/td><td class=\"column-12\"><br \/>\n                                                            <\/td><td class=\"column-13\"><br \/>\n                                                            <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n <\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>2HPA Tandem CNC Press Brake The 2HPA tandem press brake is engineered with remarkable flexibility, making it ideal for handling a diverse array of bending tasks. This machine excels in managing the bending of long workpieces, such as 12-meter light poles, with precision and ease. Furthermore, its capability to operate both independently and in tandem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":84,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-221","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/pages\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/comments?post=221"}],"version-history":[{"count":6,"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/pages\/221\/revisions"}],"predecessor-version":[{"id":608,"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/pages\/221\/revisions\/608"}],"up":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/pages\/84"}],"wp:attachment":[{"href":"https:\/\/cn-hawe.com\/it\/wp-json\/wp\/v2\/media?parent=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}