{"id":206,"date":"2025-02-08T05:43:12","date_gmt":"2025-02-08T05:43:12","guid":{"rendered":"https:\/\/cn-hawe.com\/?page_id=206"},"modified":"2025-02-11T08:45:56","modified_gmt":"2025-02-11T08:45:56","slug":"electric-servo-e-bend-press-brake","status":"publish","type":"page","link":"https:\/\/cn-hawe.com\/pt\/press-brake\/electric-servo-e-bend-press-brake\/","title":{"rendered":"HPE Servo El\u00e9trico E-Bend Press Brake"},"content":{"rendered":"<section class=\"bde-section-206-100 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-columns-206-101 bde-columns\"><div class=\"bde-column-206-102 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-104 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Electric-Servo-E-Bend-Press-Brake-2.webp\" alt=\"HPE Servo El\u00e9trico E-Bend Press Brake\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Electric-Servo-E-Bend-Press-Brake-2.webp 1500w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Electric-Servo-E-Bend-Press-Brake-2-300x210.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Electric-Servo-E-Bend-Press-Brake-2-1024x717.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Electric-Servo-E-Bend-Press-Brake-2-768x538.webp 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\">\n<\/div><div class=\"bde-column-206-103 bde-column\">\n  \n  \n\t\n\n\n\n<h1 class=\"bde-heading-206-105 bde-heading\">\nHPE Servo El\u00e9trico E-Bend Press Brake\n<\/h1><div class=\"bde-fancy-divider-206-106 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-107 bde-text\">\nA HPE Electric Servo E-Bend Press Brake \u00e9 uma solu\u00e7\u00e3o inovadora e de alto desempenho, concebida para tarefas de conforma\u00e7\u00e3o de metal de elevada precis\u00e3o. Utiliza tecnologia servo-el\u00e9trica avan\u00e7ada para alcan\u00e7ar uma precis\u00e3o excecional e efici\u00eancia operacional nos processos de dobragem. Como op\u00e7\u00e3o fi\u00e1vel, eficiente e adapt\u00e1vel para as necessidades modernas de conforma\u00e7\u00e3o de metal, destaca-se como um membro de destaque da gama de prensas dobradeiras CN-HAWE. A sua tecnologia de ponta, constru\u00e7\u00e3o dur\u00e1vel e design ergon\u00f3mico garantem que seja uma adi\u00e7\u00e3o valiosa a qualquer ambiente industrial, proporcionando precis\u00e3o e produtividade superiores, ao mesmo tempo que prioriza a seguran\u00e7a do operador e a facilidade de manuten\u00e7\u00e3o.\n<\/div><img decoding=\"async\" class=\"bde-image2-206-108 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s.webp 387w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/single_s-300x81.webp 300w\" sizes=\"(max-width: 387px) 100vw, 387px\"><div class=\"bde-button-206-109 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">CONSULTE AGORA<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><\/div><\/div>\n<\/section><section class=\"bde-section-206-110 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-div-206-121 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-111 bde-columns\"><div class=\"bde-column-206-115 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-116 bde-heading\">\nControlador CNC Avan\u00e7ado\n<\/h2><div class=\"bde-fancy-divider-206-117 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-118 bde-text\">\nEquipada com um sistema de controlo CNC avan\u00e7ado, a HPE Electric Servo E-Bend Press Brake oferece programa\u00e7\u00e3o simples e manuseamento eficiente de opera\u00e7\u00f5es de dobragem complexas. A sua interface intuitiva garante facilidade de utiliza\u00e7\u00e3o, mesmo para operadores com pouca experi\u00eancia. Al\u00e9m disso, oferecemos a possibilidade de equipar o mesmo sistema de controlo utilizado na s\u00e9rie principal HPA, juntamente com sistemas espec\u00edficos para modelos el\u00e9tricos de fabricantes renomados como Delem, Cybelec e ESA. Isto reduz significativamente a curva de aprendizagem para clientes que adotam a s\u00e9rie HPE.  \n<\/div><div class=\"bde-button-206-120 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-113 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-114 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Advanced-CNC-Controller.webp\" alt=\"Controlador CNC Avan\u00e7ado\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Advanced-CNC-Controller.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Advanced-CNC-Controller-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Advanced-CNC-Controller-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/HPE-Advanced-CNC-Controller-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-149 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-150 bde-columns\"><div class=\"bde-column-206-151 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-152 bde-heading\">\nTecnologia Servo-el\u00e9trica\n<\/h2><div class=\"bde-fancy-divider-206-153 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-154 bde-text\">\nA combina\u00e7\u00e3o da tecnologia servo e el\u00e9trica permite um controlo preciso dos processos de dobragem, proporcionando um desempenho de alta velocidade com baixo consumo de energia. Esta inova\u00e7\u00e3o aumenta a produtividade enquanto reduz as despesas operacionais.\n<\/div><div class=\"bde-button-206-235 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-156 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-157 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Servo-electric-Technology.webp\" alt=\"Tecnologia Servo-el\u00e9trica\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Servo-electric-Technology.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Servo-electric-Technology-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Servo-electric-Technology-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Servo-electric-Technology-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-158 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-159 bde-columns\"><div class=\"bde-column-206-160 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-161 bde-heading\">\nAlta Precis\u00e3o e Consist\u00eancia\n<\/h2><div class=\"bde-fancy-divider-206-162 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-163 bde-text\">\nO sistema de acionamento servo-el\u00e9trico, aliado a um posicionamento de r\u00e9gua traseira altamente preciso, garante resultados fi\u00e1veis e exatos em cada opera\u00e7\u00e3o. Esta precis\u00e3o \u00e9 essencial para as ind\u00fastrias metal\u00fargicas que exigem toler\u00e2ncias rigorosas e acabamentos superficiais superiores. A equipa de engenharia da CN-HAWE analisou minuciosamente o design estrutural e os princ\u00edpios de funcionamento da s\u00e9rie HPE, refinando cuidadosamente os benef\u00edcios \u00fanicos destes modelos totalmente el\u00e9tricos.\n<\/div><div class=\"bde-button-206-236 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-165 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-166 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/High-Precision-and-Consistency.webp\" alt=\"Alta Precis\u00e3o e Consist\u00eancia\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/High-Precision-and-Consistency.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/High-Precision-and-Consistency-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/High-Precision-and-Consistency-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/High-Precision-and-Consistency-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-167 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-168 bde-columns\"><div class=\"bde-column-206-169 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-170 bde-heading\">\nOp\u00e7\u00f5es de Dobra Vers\u00e1teis\n<\/h2><div class=\"bde-fancy-divider-206-171 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-172 bde-text\">\nA HPE Electric Servo E-Bend Press Brake \u00e9 projetada para lidar com uma ampla variedade de aplica\u00e7\u00f5es de dobragem, desde opera\u00e7\u00f5es simples a configura\u00e7\u00f5es complexas. A sua adaptabilidade torna-a perfeita para diversos requisitos de fabrico, tais como os dos setores autom\u00f3vel, eletr\u00f3nica 3C e produ\u00e7\u00e3o geral de chapas met\u00e1licas.\n<\/div><div class=\"bde-button-206-237 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-174 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-175 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Versatile-Bending-Options.webp\" alt=\"Op\u00e7\u00f5es de Dobra Vers\u00e1teis\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Versatile-Bending-Options.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Versatile-Bending-Options-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Versatile-Bending-Options-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Versatile-Bending-Options-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-176 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-177 bde-columns\"><div class=\"bde-column-206-178 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-179 bde-heading\">\nEstrutura Dur\u00e1vel\n<\/h2><div class=\"bde-fancy-divider-206-180 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-181 bde-text\">\nProjetada para durabilidade e desempenho, esta prensa dobradeira apresenta uma estrutura robusta e componentes de qualidade premium que garantem fiabilidade duradoura. A sua constru\u00e7\u00e3o s\u00f3lida torna-a ideal para opera\u00e7\u00f5es de alta velocidade em ambientes industriais exigentes.<br><br>A estrutura da HPE Electric Servo E-Bend Press Brake \u00e9 fabricada atrav\u00e9s de um processo de produ\u00e7\u00e3o preciso e meticuloso, com \u00eanfase na qualidade e precis\u00e3o excecionais. \u00c9 maquinada num moderno centro de maquina\u00e7\u00e3o CNC penta\u00e9drico, que oferece precis\u00e3o incompar\u00e1vel em opera\u00e7\u00f5es multieixo. Esta abordagem avan\u00e7ada garante que todas as superf\u00edcies de montagem atinjam paralelismo e perpendicularidade perfeitos, essenciais para o desempenho est\u00e1vel e preciso da prensa dobradeira.\n<\/div><div class=\"bde-button-206-238 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-183 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-184 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Durable-Frame.webp\" alt=\"Estrutura Dur\u00e1vel\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Durable-Frame.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Durable-Frame-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Durable-Frame-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Durable-Frame-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-185 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-186 bde-columns\"><div class=\"bde-column-206-187 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-188 bde-heading\">\nEfici\u00eancia Energ\u00e9tica\n<\/h2><div class=\"bde-fancy-divider-206-189 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-190 bde-text\">\nO sistema de acionamento servo-el\u00e9trico oferece benef\u00edcios duplos: desempenho aprimorado e maior efici\u00eancia energ\u00e9tica. Ao consumir menos energia durante a opera\u00e7\u00e3o, a HPE Electric Servo E-Bend Press Brake ajuda a reduzir significativamente a pegada de carbono do seu processo de fabrico.<br><br>Embora o custo inicial da tecnologia servo-el\u00e9trica seja mais elevado, os benef\u00edcios a m\u00e9dio prazo superam amplamente o investimento inicial, com a efici\u00eancia energ\u00e9tica destacando-se como uma vantagem crucial.\n<\/div><div class=\"bde-button-206-239 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-192 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-193 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Energy-Efficiency-1.webp\" alt=\"Efici\u00eancia Energ\u00e9tica\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Energy-Efficiency-1.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Energy-Efficiency-1-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Energy-Efficiency-1-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Energy-Efficiency-1-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><div class=\"bde-div-206-244 bde-div\">\n              \n  \n  \n\t\n\n  <div class=\"section-background-overlay\"><\/div>\n\n\n<div class=\"bde-columns-206-245 bde-columns\"><div class=\"bde-column-206-246 bde-column\">\n  \n  \n\t\n\n\n\n<h2 class=\"bde-heading-206-247 bde-heading\">\nFuncionalidades de Seguran\u00e7a Refor\u00e7adas\n<\/h2><div class=\"bde-fancy-divider-206-248 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator\">\n  \t  <\/div>\n<\/div>\n\n<\/div><div class=\"bde-text-206-249 bde-text\">\nGarantir a seguran\u00e7a \u00e9 fundamental, com a inclus\u00e3o de recursos como barreiras de prote\u00e7\u00e3o a laser, controlos de paragem de emerg\u00eancia e intertravamentos de seguran\u00e7a concebidos para proteger os operadores durante a utiliza\u00e7\u00e3o. Estas medidas minimizam eficazmente o risco de acidentes, promovendo um ambiente de trabalho mais seguro.\n<\/div><div class=\"bde-button-206-250 bde-button\">\n        \n    \n    \n    \n    \n            \n                    \n            \n                           \n                       \n                 \n\n    \n    \n    \n                    \n    \n    <a class=\"breakdance-link button-atom button-atom--primary bde-button__button\" href=\"#\" target=\"_self\" data-type=\"action\"  data-action='{\"type\":\"popup\",\"popupOptions\":{\"popupId\":\"176\",\"popupAction\":\"open\"}}' >\n\n    \n        <span class=\"button-atom__text\">OBTENHA OR\u00c7AMENTO GRATUITO<\/span>\n\n        \n        \n                <\/a>\n\n    \n\n\n<\/div>\n<\/div><div class=\"bde-column-206-251 bde-column\">\n  \n  \n\t\n\n\n\n<img decoding=\"async\" class=\"bde-image2-206-252 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Enhanced-Safety-Features.webp\" alt=\"Funcionalidades de Seguran\u00e7a Refor\u00e7adas\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Enhanced-Safety-Features.webp 1200w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Enhanced-Safety-Features-300x225.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Enhanced-Safety-Features-1024x768.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Enhanced-Safety-Features-768x576.webp 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\">\n<\/div><\/div>\n<\/div><\/div>\n<\/section><section class=\"bde-section-206-230 bde-section\">\n  \n  \n\t\n\n\n\n<div class=\"section-container\"><div class=\"bde-fancy-divider-206-232 bde-fancy-divider\">\n\n\n<div class=\"bde-fancy-divider__wrapper\">\n  <div class=\"bde-fancy-divider__separator has-content\">\n  \t    \t    \t          <h2 class=\"bde-fancy-divider__content bde-fancy-divider__content--text\">\n          Especifica\u00e7\u00f5es T\u00e9cnicas\n          <\/h2>\n    \t      <\/div>\n<\/div>\n\n<\/div><img decoding=\"async\" class=\"bde-image2-206-233 bde-image2\" src=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3.webp\" loading=\"lazy\" srcset=\"https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3.webp 1300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-300x92.webp 300w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-1024x315.webp 1024w, https:\/\/cn-hawe.com\/wp-content\/uploads\/2025\/02\/Technical-Specifications-3-768x236.webp 768w\" sizes=\"(max-width: 1300px) 100vw, 1300px\"><div class=\"bde-shortcodewrapper-206-234 bde-shortcodewrapper\">\n<table id=\"tablepress-4\" class=\"tablepress tablepress-id-4\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><br \/>\n                                        Modelo                    <\/th><th class=\"column-2\"><br \/>\n                                        For\u00e7a de Dobragem                    <\/th><th class=\"column-3\"><br \/>\n                                        Comprimento de Dobra<br \/>\n(A)                    <\/th><th class=\"column-4\"><br \/>\n                                        Dep\u00f3sito de \u00d3leo                    <\/th><th class=\"column-5\"><br \/>\n                                        Velocidade de Aproxima\u00e7\u00e3o                    <\/th><th class=\"column-6\"><br \/>\n                                        Taxa de Progresso                    <\/th><th class=\"column-7\"><br \/>\n                                        Velocidade de Retorno                    <\/th><th class=\"column-8\"><br \/>\n                                        Dist\u00e2ncia entre Colunas<br \/>\n(B)                    <\/th><th class=\"column-9\"><br \/>\n                                        Profundidade da garganta<br \/>\n(C)                    <\/th><th class=\"column-10\"><br \/>\n                                        Curso do deslizador<br \/>\n(D)                    <\/th><th class=\"column-11\"><br \/>\n                                        Altura aberta<br \/>\n(E)                    <\/th><th class=\"column-12\"><br \/>\n                                        Motor Principal                    <\/th><th class=\"column-13\"><br \/>\n                                        Dimens\u00f5es                    <\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><br \/>\n                                        Unidade                    <\/td><td class=\"column-2\"><br \/>\n                                        kN                    <\/td><td class=\"column-3\"><br \/>\n                                        mm                    <\/td><td class=\"column-4\"><br \/>\n                                        L                    <\/td><td class=\"column-5\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-6\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-7\"><br \/>\n                                        mm\/s                    <\/td><td class=\"column-8\"><br \/>\n                                        mm                    <\/td><td class=\"column-9\"><br \/>\n                                        mm                    <\/td><td class=\"column-10\"><br \/>\n                                        mm                    <\/td><td class=\"column-11\"><br \/>\n                                        mm                    <\/td><td class=\"column-12\"><br \/>\n                                        KW                    <\/td><td class=\"column-13\"><br \/>\n                                        L*A*P (mm)                    <\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\"><br \/>\n                                        HPE-50\/1500                    <\/td><td class=\"column-2\"><br \/>\n                                        500                    <\/td><td class=\"column-3\"><br \/>\n                                        1500                    <\/td><td class=\"column-4\"><br \/>\n                                        \/                    <\/td><td class=\"column-5\"><br \/>\n                                        230                    <\/td><td class=\"column-6\"><br \/>\n                                        25                    <\/td><td class=\"column-7\"><br \/>\n                                        230                    <\/td><td class=\"column-8\"><br \/>\n                                        1150                    <\/td><td class=\"column-9\"><br \/>\n                                        350                    <\/td><td class=\"column-10\"><br \/>\n                                        180                    <\/td><td class=\"column-11\"><br \/>\n                                        490                    <\/td><td class=\"column-12\"><br \/>\n                                        2*18KW                    <\/td><td class=\"column-13\"><br \/>\n                                        1720*1500*2400                    <\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\"><br \/>\n                                        HPE-50\/1600                    <\/td><td class=\"column-2\"><br \/>\n                                        500                    <\/td><td class=\"column-3\"><br \/>\n                                        1600                    <\/td><td class=\"column-4\"><br \/>\n                                        \/                    <\/td><td class=\"column-5\"><br \/>\n                                        260                    <\/td><td class=\"column-6\"><br \/>\n                                        25                    <\/td><td class=\"column-7\"><br \/>\n                                        260                    <\/td><td class=\"column-8\"><br \/>\n                                        1150                    <\/td><td class=\"column-9\"><br \/>\n                                        350                    <\/td><td class=\"column-10\"><br \/>\n                                        180                    <\/td><td class=\"column-11\"><br \/>\n                                        490                    <\/td><td class=\"column-12\"><br \/>\n                                        2*7,5KW                    <\/td><td class=\"column-13\"><br \/>\n                                        1820*1500*2680                    <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-4 from cache --> <\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>HPE Electric Servo E-Bend Press Brake The HPE Electric Servo E-Bend Press Brake is an innovative, high-performance solution tailored for precise metal forming tasks. It utilizes advanced servo-electric technology to achieve exceptional accuracy and operational efficiency in bending processes. As a dependable, efficient, and adaptable option for contemporary metal forming needs, it stands out as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":84,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_breakdance_hide_in_design_set":false,"_breakdance_tags":"","footnotes":""},"class_list":["post-206","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/pages\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":5,"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/pages\/206\/revisions"}],"predecessor-version":[{"id":609,"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/pages\/206\/revisions\/609"}],"up":[{"embeddable":true,"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/pages\/84"}],"wp:attachment":[{"href":"https:\/\/cn-hawe.com\/pt\/wp-json\/wp\/v2\/media?parent=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}